{"id":39945,"date":"2025-07-15T11:14:55","date_gmt":"2025-07-15T11:14:55","guid":{"rendered":"https:\/\/stella-pss.eu\/?p=39945"},"modified":"2025-07-15T13:17:06","modified_gmt":"2025-07-15T13:17:06","slug":"stella-featured-at-mpu-2025-bari","status":"publish","type":"post","link":"https:\/\/stella-pss.eu\/fr\/stella-featured-at-mpu-2025-bari\/","title":{"rendered":"STELLA mis en avant au MPU 2025 | Bari"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"39945\" class=\"elementor elementor-39945\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6ca076f0 e-flex e-con-boxed sc_layouts_column_icons_position_left e-con e-parent\" data-id=\"6ca076f0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-46a701c sc_fly_static elementor-widget elementor-widget-text-editor\" data-id=\"46a701c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b><i>Par Dimitra Fourkalidou | Responsable de la communication | reframe.food<\/i><\/b><\/p><p>Le 17\u1d49 Congr\u00e8s international de l\u2019Union Phytopathologique M\u00e9diterran\u00e9enne (MPU 2025), qui s\u2019est tenu du 6 au 10 juillet 2025 au CIHEAM de Bari, a r\u00e9uni des pathologistes v\u00e9g\u00e9taux et chercheurs de premier plan pour explorer de nouvelles fronti\u00e8res en phytopathologie et s\u00e9curit\u00e9 alimentaire. Sous le th\u00e8me \u00ab Nouvelles fronti\u00e8res de la recherche et de l\u2019\u00e9ducation en phytopathologie pour la sant\u00e9 des plantes et la s\u00e9curit\u00e9 alimentaire \u00bb, le congr\u00e8s a mis en lumi\u00e8re les innovations de pointe et les strat\u00e9gies collaboratives pour un avenir agroalimentaire plus durable et s\u00fbr.<\/p><p>Le STELLA Pest Surveillance System (STELLA PSS) a \u00e9t\u00e9 particuli\u00e8rement mis en avant gr\u00e2ce aux interventions de l\u2019\u00e9quipe de coordination et de mise en \u0153uvre du projet de l\u2019Universit\u00e9 agricole d\u2019Ath\u00e8nes.<\/p><p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/stella-pss.eu\/wp-content\/uploads\/2025\/07\/image00005-600x450.jpeg\" alt=\"\" width=\"600\" height=\"450\" \/><\/p><figure style=\"text-align: center;\">Figure 1: Prof. Dimitris Tsitsigiannis presenting STELLA at a glance. <br \/>Cr\u00e9dit : Agricultural University of Athens<\/figure><h4 style=\"text-align: left;\"><strong>Technologies num\u00e9riques avanc\u00e9es pour la d\u00e9tection des maladies v\u00e9g\u00e9tales<\/strong><\/h4><p>Lors de la journ\u00e9e d\u2019ouverture, le Prof. Dimitris Tsitsigiannis, coordinateur du projet STELLA et pr\u00e9sident de la MPU, a pr\u00e9sent\u00e9 une conf\u00e9rence intitul\u00e9e:\u00a0<span style=\"font-size: 17px; letter-spacing: 0px;\">\u00ab Technologies num\u00e9riques intelligentes et IA pour la d\u00e9tection des maladies v\u00e9g\u00e9tales, la surveillance territoriale et les mesures de contr\u00f4le \u00bb.<\/span><\/p><p>Sa pr\u00e9sentation a explor\u00e9 l\u2019int\u00e9gration de l\u2019IA, de l\u2019IoT et des outils num\u00e9riques dans les strat\u00e9gies de suivi sanitaire des plantes. Il a montr\u00e9 comment la convergence des syst\u00e8mes d\u2019alerte pr\u00e9coce, des donn\u00e9es en temps r\u00e9el issues de capteurs, du diagnostic bas\u00e9 sur l\u2019imagerie et des technologies de pulv\u00e9risation de pr\u00e9cision transforme la Gestion Int\u00e9gr\u00e9e des Ravageurs (IPM) en Europe. Cette approche favorise l\u2019agriculture durable en permettant des interventions pr\u00e9coces, en r\u00e9duisant l\u2019usage de pesticides et en renfor\u00e7ant la r\u00e9silience face aux maladies \u00e9mergentes des plantes. Elle alimente directement la m\u00e9thodologie de STELLA et souligne son alignement avec les objectifs europ\u00e9ens de transition verte et num\u00e9rique dans la sant\u00e9 v\u00e9g\u00e9tale.<\/p><p class=\"translation-block\">Le Prof. Tsitsigiannis a exprim\u00e9 sa reconnaissance pour avoir ouvert le congr\u00e8s, notant que \u00ab <em>discuter des technologies num\u00e9riques intelligentes pour la GIP et des strat\u00e9gies pour prot\u00e9ger la sant\u00e9 des plantes et assurer la s\u00e9curit\u00e9 alimentaire <\/em>\u00bb fut un honneur. Il a ajout\u00e9 que \u00ab<em> l\u2019\u00e9change d\u2019id\u00e9es et les collaborations ont \u00e9t\u00e9 tr\u00e8s inspirants<\/em> \u00bb, et soulign\u00e9 que \u00ab <em>ensemble, nous faisons progresser la science pour un avenir plus sain et durable<\/em> \u00bb.<\/p><h4 style=\"text-align: left;\"><strong>Poster : Cas pilotes STELLA en Gr\u00e8ce<\/strong><\/h4><p>Un poster intitul\u00e9 \u00ab Int\u00e9gration des outils num\u00e9riques pour la sant\u00e9 des plantes : Cas pilotes du STELLA Pest Surveillance System en Gr\u00e8ce \u00bb, co-r\u00e9dig\u00e9 par Spyridoula Dimitropoulou<span style=\"font-family: Roboto, sans-serif; font-size: 17px; font-style: normal; font-weight: 400; letter-spacing: 0px;\">(chercheuse associ\u00e9e, Laboratoire de Pathologie V\u00e9g\u00e9tale, AUA)<\/span><span style=\"font-size: 17px; letter-spacing: 0px;\">\u00a0et le Prof. Tsitsigiannis, a d\u00e9taill\u00e9 les applications r\u00e9elles de STELLA sur deux cas pilotes en Gr\u00e8ce.<\/span><\/p><p><img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/stella-pss.eu\/wp-content\/uploads\/2025\/07\/MPU-2025-2-1-556x600.jpeg\" alt=\"\" width=\"556\" height=\"600\" \/><\/p><figure style=\"text-align: center;\">Figure 2: Spyridoula Dimitropoulou &#8211; Poster.<br \/>Cr\u00e9dit : Agricultural University of Athens<\/figure><p>Le STELLA PSS est actuellement d\u00e9ploy\u00e9 pour surveiller et g\u00e9rer trois agents pathog\u00e8nes majeurs:<\/p><ul><li>Ceratocystis platani, champignon quarantenaire responsable du canker stain chez les platanes ;<\/li><li>Verticillium dahliae, agent de la verticilliose ;<\/li><li>Pseudomonas savastanoi pv. savastanoi, responsable de la maladie du nodule de l\u2019olivier.<\/li><\/ul><p>Ces cas pilotes sont implant\u00e9s dans des environnements vari\u00e9s, de la for\u00eat riveraine de Kireas sur l\u2019\u00eele d\u2019Evia aux oliveraies commerciales d\u2019Atalanti et d\u2019Attique, d\u00e9montrant la polyvalence et l\u2019\u00e9volutivit\u00e9 du syst\u00e8me. Il combine capteurs IoT sur site, imagerie UAV et satellite, outils de d\u00e9tection proximale comme EDEN Viewer, et mod\u00e9lisation spatio-temporelle pour offrir une surveillance proactive et haute r\u00e9solution, tout en favorisant la surveillance participative via applications mobiles et science citoyenne.<\/p><h4 style=\"text-align: left;\"><b>Vid\u00e9o prim\u00e9e : Protection des platanes<\/b><\/h4><p style=\"text-align: justify;\" class=\"translation-block\">Lors de la session pl\u00e9ni\u00e8re de cl\u00f4ture, Spyridoula Dimitropoulou a pr\u00e9sent\u00e9 la vid\u00e9o prim\u00e9e : \u00ab Sauver les platanes de Gr\u00e8ce : Technologie num\u00e9rique pour la d\u00e9tection pr\u00e9coce de Ceratocystis platani \u2013 Cas pilote grec \u00bb.<\/p><p style=\"text-align: justify;\"><span style=\"color: #656565;\"><span style=\"font-size: 17px; letter-spacing: normal; text-transform: none;\">Cette vid\u00e9o a remport\u00e9 le 1er prix du concours vid\u00e9o Euphresco III Plant Health et illustre l\u2019approche innovante et interdisciplinaire de STELLA pour prot\u00e9ger le Platanus orientalis gr\u00e2ce \u00e0 des outils num\u00e9riques avanc\u00e9s.<\/span><\/span><\/p><p class=\"translation-block\">Spyridoula a expliqu\u00e9 l\u2019importance de la d\u00e9tection pr\u00e9coce pour prot\u00e9ger la biodiversit\u00e9 urbaine et a soulign\u00e9 que participer au MPU 2025 avait \u00e9t\u00e9 inspirant et enrichissant, ouvrant de nouvelles opportunit\u00e9s de collaboration transfrontali\u00e8re. Elle a ajout\u00e9 : \u00ab Gagner le concours vid\u00e9o Euphresco III a \u00e9t\u00e9 un moment m\u00e9morable qui montre le pouvoir de la communication scientifique \u00bb.<\/p><p><img decoding=\"async\" class=\"aligncenter\" style=\"font-family: inherit; font-style: inherit; font-weight: inherit; letter-spacing: 0px;\" src=\"https:\/\/stella-pss.eu\/wp-content\/uploads\/2025\/07\/image00033-600x400.jpeg\" alt=\"\" width=\"600\" height=\"400\" \/><\/p><figure style=\"text-align: center;\">Figure 3: Spyridoula Dimitropoulou &#8211; First prize in the Euphresco III Plant Health Video Contest. <br \/>Cr\u00e9dit : Agricultural University of Athens<\/figure><h4 style=\"text-align: left;\"><strong>Un futur num\u00e9rique et scientifique pour la sant\u00e9 des plantes<\/strong><\/h4><p>La visibilit\u00e9 et la reconnaissance de STELLA au MPU 2025 confirment le r\u00f4le de premier plan du projet dans le d\u00e9veloppement de solutions intelligentes, num\u00e9riques et \u00e9volutives pour la surveillance des ravageurs. La combinaison d\u2019excellence scientifique, de d\u00e9ploiement pratique et d\u2019engagement des parties prenantes illustre la contribution de STELLA aux politiques europ\u00e9ennes en sant\u00e9 v\u00e9g\u00e9tale et son potentiel de r\u00e9plication dans les syst\u00e8mes agricoles m\u00e9diterran\u00e9ens et europ\u00e9ens.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>By Dimitra Fourkalidou | Head of Communications | reframe.food The 17th International Congress of the&hellip;<\/p>","protected":false},"author":2,"featured_media":39946,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"iawp_total_views":52,"footnotes":""},"categories":[136,138],"tags":[],"class_list":["post-39945","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","category-project-news"],"_links":{"self":[{"href":"https:\/\/stella-pss.eu\/fr\/wp-json\/wp\/v2\/posts\/39945","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stella-pss.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/stella-pss.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/stella-pss.eu\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/stella-pss.eu\/fr\/wp-json\/wp\/v2\/comments?post=39945"}],"version-history":[{"count":0,"href":"https:\/\/stella-pss.eu\/fr\/wp-json\/wp\/v2\/posts\/39945\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stella-pss.eu\/fr\/wp-json\/wp\/v2\/media\/39946"}],"wp:attachment":[{"href":"https:\/\/stella-pss.eu\/fr\/wp-json\/wp\/v2\/media?parent=39945"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/stella-pss.eu\/fr\/wp-json\/wp\/v2\/categories?post=39945"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/stella-pss.eu\/fr\/wp-json\/wp\/v2\/tags?post=39945"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}